{"id":29813,"date":"2024-08-01T08:29:33","date_gmt":"2024-08-01T14:29:33","guid":{"rendered":"https:\/\/mujeresmsm.org\/?p=29813"},"modified":"2024-08-01T18:20:54","modified_gmt":"2024-08-02T00:20:54","slug":"fortalecimiento-impulso-y-acompanamiento-de-dos-2-ventanas-ciudadanas","status":"publish","type":"post","link":"https:\/\/mujeresmsm.org\/en\/proyectos-en-ejecucion\/fortalecimiento-impulso-y-acompanamiento-de-dos-2-ventanas-ciudadanas\/","title":{"rendered":"Fortalecimiento, impulso y acompa\u00f1amiento de dos (2) Ventanas Ciudadanas"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"29813\" class=\"elementor elementor-29813\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4fd64a10 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"4fd64a10\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0762ef9 elementor-widget elementor-widget-text-editor\" data-id=\"0762ef9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>PROYECTO:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8a9172 elementor-widget elementor-widget-heading\" data-id=\"c8a9172\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Empoderando mujeres juventudes prevenci\u00f3n g\u00e9nero municipio San Mart\u00edn<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e619100 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"6e619100\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-154a34c4 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"154a34c4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50bd2dff elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"50bd2dff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Fortalecimiento, impulso y acompa\u00f1amiento de dos (2) Ventanas Ciudadanas<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-376aa58 elementor-widget elementor-widget-text-editor\" data-id=\"376aa58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En estos momentos existen dos Ventanas Ciudadanas en el municipio, si bien las cuales no est\u00e1n en funcionamiento. A trav\u00e9s del proyecto se promover\u00e1 la reactivaci\u00f3n de las mismas, el fortalecimiento, impulso y acompa\u00f1amiento de ambas.<\/p><p>Se fortalecer\u00e1n las 2 Ventanas Ciudadanas en el Municipio, de las que forman parte las lideresas de las comunidades. Estas mujeres tienen una trayectoria previa, por lo que sus necesidades son de acompa\u00f1amiento t\u00e9cnico y apoyo econ\u00f3mico para el desarrollo de su funci\u00f3n.<\/p><p>La formaci\u00f3n se centrar\u00e1 en el Protocolo de atenci\u00f3n a mujeres v\u00edctimas de violencia que utiliza el Instituto de Desarrollo de la Mujer Salvadore\u00f1a ISDEMU, para que las mujeres conozcan c\u00f3mo debe ser la atenci\u00f3n de las instituciones (policiales, sanitarias, judiciales) cuando han sufrido un hecho de violencia. Los objetivos de este Protocolo son:<\/p><ol><li>Brindar un servicio de atenci\u00f3n especializada e integral a las mujeres que enfrentan Violencia Basada en G\u00e9nero (VBG).<\/li><li>Garantizar el cumplimiento de los DDHH de las mujeres que enfrentan violencia y que solicitan atenci\u00f3n especializada del ISDEMU.<\/li><li>Estandarizar los procedimientos institucionales de abordaje para los casos de mujeres que enfrentan VG, que se reciben en las diferentes unidades de ISDEMU.<\/li><li>Identificar las \u00e1reas de trabajo implicadas en la atenci\u00f3n a mujeres que enfrentan VG, detallando la ruta de actuaci\u00f3n en cada tipolog\u00eda, promoviendo una intervenci\u00f3n integral de todas las instituciones del Estado implicadas en la atenci\u00f3n a la VG.<\/li><\/ol>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-356d4424 elementor-widget elementor-widget-text-editor\" data-id=\"356d4424\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Agencia de cooperaci\u00f3n:<\/strong><\/p><ul><li>Instituto Sindicala de Cooperaci\u00f3n al Desarrollo (ISCOD) &#8211; Gobierno de Navarra<\/li><\/ul><p>\u00a0<\/p><p><strong>Ubicaci\u00f3n:<\/strong><\/p><ul><li>San Martin<\/li><\/ul><p>\u00a0<\/p><p><strong>Fecha de inicio y finalizaci\u00f3n:<\/strong><\/p><ul><li>Inicia: 07 de nov 2023 finaliza: 06 de nov 2024 (duraci\u00f3n 12 meses)<\/li><\/ul><p>\u00a0<\/p><p><strong>Plazo:<\/strong><\/p><ul><li>1 a\u00f1o<\/li><\/ul><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2741c5e9 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"2741c5e9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1fa718a7 elementor-widget elementor-widget-gallery\" data-id=\"1fa718a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;columns&quot;:3,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;gallery_layout&quot;:&quot;masonry&quot;,&quot;overlay_title&quot;:&quot;caption&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2024\/08\/700eb83a-5dde-4c6c-9884-7abf5d4d9366-2.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1fa718a7\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjk4MDksInVybCI6Imh0dHBzOlwvXC9tdWplcmVzbXNtLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDhcLzcwMGViODNhLTVkZGUtNGM2Yy05ODg0LTdhYmY1ZDRkOTM2Ni0yLmpwZWciLCJzbGlkZXNob3ciOiIxZmE3MThhNyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2024\/08\/700eb83a-5dde-4c6c-9884-7abf5d4d9366-2-300x151.jpeg\" data-width=\"300\" data-height=\"151\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2024\/08\/35d68f5b-6d57-4560-ae3e-a27fe360507e-3.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1fa718a7\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjk4MDgsInVybCI6Imh0dHBzOlwvXC9tdWplcmVzbXNtLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDhcLzM1ZDY4ZjViLTZkNTctNDU2MC1hZTNlLWEyN2ZlMzYwNTA3ZS0zLmpwZWciLCJzbGlkZXNob3ciOiIxZmE3MThhNyJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2024\/08\/35d68f5b-6d57-4560-ae3e-a27fe360507e-3-300x178.jpeg\" data-width=\"300\" data-height=\"178\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2024\/08\/1ce3d786-9cd2-47d2-a74e-a0dec581701c.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1fa718a7\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjk4MDcsInVybCI6Imh0dHBzOlwvXC9tdWplcmVzbXNtLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDhcLzFjZTNkNzg2LTljZDItNDdkMi1hNzRlLWEwZGVjNTgxNzAxYy5qcGVnIiwic2xpZGVzaG93IjoiMWZhNzE4YTcifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2024\/08\/1ce3d786-9cd2-47d2-a74e-a0dec581701c-300x226.jpeg\" data-width=\"300\" data-height=\"226\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2024\/08\/41c58fdd-f29f-44a2-bdd8-74a1e776c3fa.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1fa718a7\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjk4MDYsInVybCI6Imh0dHBzOlwvXC9tdWplcmVzbXNtLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDhcLzQxYzU4ZmRkLWYyOWYtNDRhMi1iZGQ4LTc0YTFlNzc2YzNmYS5qcGVnIiwic2xpZGVzaG93IjoiMWZhNzE4YTcifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2024\/08\/41c58fdd-f29f-44a2-bdd8-74a1e776c3fa-300x226.jpeg\" data-width=\"300\" data-height=\"226\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2024\/08\/528167e6-712a-4cac-820a-f840a01bb3d2.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1fa718a7\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjk4MDUsInVybCI6Imh0dHBzOlwvXC9tdWplcmVzbXNtLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDhcLzUyODE2N2U2LTcxMmEtNGNhYy04MjBhLWY4NDBhMDFiYjNkMi5qcGVnIiwic2xpZGVzaG93IjoiMWZhNzE4YTcifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2024\/08\/528167e6-712a-4cac-820a-f840a01bb3d2-300x226.jpeg\" data-width=\"300\" data-height=\"226\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2024\/08\/d25c0796-2c40-4aad-a85f-efd0930c7213.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1fa718a7\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjk4MDQsInVybCI6Imh0dHBzOlwvXC9tdWplcmVzbXNtLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDhcL2QyNWMwNzk2LTJjNDAtNGFhZC1hODVmLWVmZDA5MzBjNzIxMy5qcGVnIiwic2xpZGVzaG93IjoiMWZhNzE4YTcifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2024\/08\/d25c0796-2c40-4aad-a85f-efd0930c7213-300x121.jpeg\" data-width=\"300\" data-height=\"121\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-03-19-at-11.43.34-AM.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1fa718a7\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjk4MDMsInVybCI6Imh0dHBzOlwvXC9tdWplcmVzbXNtLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDhcL1doYXRzQXBwLUltYWdlLTIwMjQtMDMtMTktYXQtMTEuNDMuMzQtQU0uanBlZyIsInNsaWRlc2hvdyI6IjFmYTcxOGE3In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-03-19-at-11.43.34-AM-226x300.jpeg\" data-width=\"226\" data-height=\"300\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-03-19-at-11.45.11-AM-1.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1fa718a7\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjk4MDIsInVybCI6Imh0dHBzOlwvXC9tdWplcmVzbXNtLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMDhcL1doYXRzQXBwLUltYWdlLTIwMjQtMDMtMTktYXQtMTEuNDUuMTEtQU0tMS5qcGVnIiwic2xpZGVzaG93IjoiMWZhNzE4YTcifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2024\/08\/WhatsApp-Image-2024-03-19-at-11.45.11-AM-1-300x226.jpeg\" data-width=\"300\" data-height=\"226\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__content\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b7688e7 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"b7688e7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-762e48e e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"762e48e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4e372d7 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"4e372d7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6312a6c elementor-widget elementor-widget-image\" data-id=\"6312a6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2024\/08\/2bced2b4-9c55-4bb0-998b-650d3fc03ea3-1024x768.jpg\" class=\"attachment-large size-large wp-image-29833\" alt=\"\" srcset=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2024\/08\/2bced2b4-9c55-4bb0-998b-650d3fc03ea3-1024x768.jpg 1024w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2024\/08\/2bced2b4-9c55-4bb0-998b-650d3fc03ea3-300x225.jpg 300w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2024\/08\/2bced2b4-9c55-4bb0-998b-650d3fc03ea3-768x576.jpg 768w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2024\/08\/2bced2b4-9c55-4bb0-998b-650d3fc03ea3-1536x1152.jpg 1536w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2024\/08\/2bced2b4-9c55-4bb0-998b-650d3fc03ea3-16x12.jpg 16w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2024\/08\/2bced2b4-9c55-4bb0-998b-650d3fc03ea3.jpg 1600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dc59bd2 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"dc59bd2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d9d991f elementor-widget elementor-widget-heading\" data-id=\"d9d991f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Desarrollo de la Escuela de Derechos Sexuales y Reproductivos, con enfoque de diversidad para las juventudes.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96800bf elementor-widget elementor-widget-text-editor\" data-id=\"96800bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Esta Escuela contribuir\u00e1 a generar reflexividad en torno a la sexualidad e identidad de g\u00e9nero, por tanto, genera posibilidades para desvelar algunas de las caracter\u00edsticas de la masculinidad hegem\u00f3nica que tanto da\u00f1o hacen a las relaciones entre los g\u00e9neros. Cada sesi\u00f3n contempla el desarrollo de conversaciones y reflexiones colectivas por parte de las y los j\u00f3venes.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6a1457 elementor-mobile-align-center elementor-tablet-align-center elementor-widget elementor-widget-button\" data-id=\"b6a1457\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Leer m\u00e1s<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>En estos momentos existen dos Ventanas Ciudadanas en el municipio, si bien las cuales no est\u00e1n en funcionamiento. A trav\u00e9s del proyecto se promover\u00e1 la reactivaci\u00f3n de las mismas, el fortalecimiento, impulso y acompa\u00f1amiento de ambas.<\/p>\n<p>Se fortalecer\u00e1n las 2 Ventanas Ciudadanas en el Municipio, de las que forman parte las lideresas de las comunidades. Estas mujeres tienen una trayectoria previa, por lo que sus necesidades son de acompa\u00f1amiento t\u00e9cnico y apoyo econ\u00f3mico para el desarrollo de su funci\u00f3n.<\/p>\n<p>La formaci\u00f3n se centrar\u00e1 en el Protocolo de atenci\u00f3n a mujeres v\u00edctimas de violencia que utiliza el Instituto de Desarrollo de la Mujer Salvadore\u00f1a ISDEMU, para que las mujeres conozcan c\u00f3mo debe ser la atenci\u00f3n de las instituciones (policiales, sanitarias, judiciales) cuando han sufrido un hecho de violencia. Los objetivos de este Protocolo son:<\/p>\n<p>a)\tBrindar un servicio de atenci\u00f3n especializada e integral a las mujeres que enfrentan Violencia Basada en G\u00e9nero (VBG).<\/p>\n<p>b)\tGarantizar el cumplimiento de los DDHH de las mujeres que enfrentan violencia y que solicitan atenci\u00f3n especializada del ISDEMU.<\/p>\n<p>c)\tEstandarizar los procedimientos institucionales de abordaje para los casos de mujeres que enfrentan VG, que se reciben en las diferentes unidades de ISDEMU.<\/p>\n<p>d)\tIdentificar las \u00e1reas de trabajo implicadas en la atenci\u00f3n a mujeres que enfrentan VG, detallando la ruta de actuaci\u00f3n en cada tipolog\u00eda, promoviendo una intervenci\u00f3n integral de todas las instituciones del Estado implicadas en la atenci\u00f3n a la VG.<\/p>","protected":false},"author":1,"featured_media":29805,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[],"class_list":["post-29813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-proyectos-en-ejecucion"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts\/29813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/comments?post=29813"}],"version-history":[{"count":19,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts\/29813\/revisions"}],"predecessor-version":[{"id":29845,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts\/29813\/revisions\/29845"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/media\/29805"}],"wp:attachment":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/media?parent=29813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/categories?post=29813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/tags?post=29813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}