{"id":29362,"date":"2023-10-01T15:40:39","date_gmt":"2023-10-01T21:40:39","guid":{"rendered":"https:\/\/mujeresmsm.org\/?p=29362"},"modified":"2024-07-27T17:40:24","modified_gmt":"2024-07-27T23:40:24","slug":"proyecto-manos-unidas-sonsonate","status":"publish","type":"post","link":"https:\/\/mujeresmsm.org\/en\/proyectos-finalizados\/proyecto-manos-unidas-sonsonate\/","title":{"rendered":"Proyecto Manos Unidas, Sonsonate"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"29362\" class=\"elementor elementor-29362\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c556cce e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"6c556cce\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-527affc4 elementor-widget elementor-widget-text-editor\" data-id=\"527affc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<p><em>\u00abMujeres y j\u00f3venes organizados defienden sus derechos econ\u00f3micos, sociales, pol\u00edticos y ambientales y promueven la prevenci\u00f3n de la violencia y la seguridad alimentaria en 4 municipios del departamento de Sonsonate\u00bb<\/em><\/p>\n\n\n\n<p><strong>Objetivo general: <\/strong>contribuir a la defensa y exigibilidad de derechos de las mujeres y j\u00f3venes, promoviendo la prevenci\u00f3n de la violencia y la autonom\u00eda econ\u00f3mica en 4 municipios del departamento de Sonsonate.<strong><\/strong><\/p>\n\n\n\n<p><strong>Breve descripci\u00f3n del proyecto:<\/strong> el proyecto: Mujeres y j\u00f3venes defienden sus derechos econ\u00f3micos, sociales, ambientales y promueven la seguridad alimentaria en 4 municipios del departamento de Sonsonate\u201d, se ejecutar\u00e1 en la zona occidental del pa\u00eds, espec\u00edficamente en el Departamento de Sonsonate, en los municipios de Santa Isabel Ishuat\u00e1n, San Juli\u00e1n, Cuisnahuat y Nahuizalco.\u00a0 Las acciones est\u00e1n dirigidas de manera directa a 1000 mujeres y 800 j\u00f3venes, de esta poblaci\u00f3n existen personas que tienen fortalecida su identidad ind\u00edgena, as\u00ed como otras personas que no se identifican como ind\u00edgenas, a pesar que sus ancestros son ind\u00edgenas locales procedentes de los 4 municipios. Indirectamente se alcanzar\u00e1 una poblaci\u00f3n estimada de 9000 entre mujeres y hombres en los 4 municipios.<\/p>\n\n\n\n<p><strong>Resultados del proyecto: <\/strong><\/p>\n\n\n\n<p>R1. Mujeres de 4 asociaciones municipales fortalecen su capacidad de liderazgo y capacidad para la prevenci\u00f3n de la violencia de g\u00e9nero y participan activamente en espacios de toma de decisiones para exigir el cumplimiento de las Pol\u00edticas Municipales de Igualdad de G\u00e9nero. <\/p>\n\n\n\n<p>R2. J\u00f3venes de 4 redes municipales fortalecen su capacidad de liderazgo y contralor\u00eda social para dar cumplimiento a las Pol\u00edticas Municipales de Juventud aprobadas. <\/p>\n\n\n\n<p>R3. Mujeres y j\u00f3venes mejoran su autonom\u00eda econ\u00f3mica, empleabilidad y seguridad alimentaria a trav\u00e9s de la capacitaci\u00f3n, el fortalecimiento de las iniciativas econ\u00f3micas y los procesos productivos y de comercializaci\u00f3n de sus productos.<\/p>\n\n\n\n<p><strong>Ubicaci\u00f3n geogr\u00e1fica:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td>Departamento:<\/td><td>Municipios:<\/td><td>Comunidades<\/td><\/tr><tr><td rowspan=\"4\">SONSONATE<\/td><td>Santa Isabel Ishuat\u00e1n<\/td><td>AcachapaLas PiedrasEl CorozalApancoyoAtiluyaMiramar<\/td><\/tr><tr><td>Cuisnahuat<\/td><td>Casco urbanoAgua ShucaCoquiamaEl BalsamarSan LucasApancoyo<\/td><\/tr><tr><td>San Juli\u00e1n<\/td><td>Casco urbanoAgua ShucaChilataLos LagartosPe\u00f1a BlancaPetacas<\/td><\/tr><tr><td>Nahuizalco<\/td><td>Sabana GrandeEl CarrizalTajcuilujlanSisimitepecPusht\u00e1nEl Cerrito<\/td><\/tr><tr><td>1 departamento<\/td><td>4 municipios<\/td><td>24 comunidades<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><strong>Que se ha ejecutado:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Socializaci\u00f3n p\u00fablica del proyecto con autoridades locales de los 4 municipios, mujeres de asociaciones municipales y juventudes.<\/li>\n\n\n\n<li>Creaci\u00f3n y puesta en marcha de 6 nuevos comit\u00e9s de mujeres en el municipio de Cuisnahuat.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>Un diagn\u00f3stico sobre el estado de los derechos humanos de las mujeres y j\u00f3venes, y la elaboraci\u00f3n de una PMIG en el municipio de Cuisnahuat.&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>Conformaci\u00f3n de una asociaci\u00f3n de mujeres en Cuisnahuat y fortalecimiento de 3 asociaciones de San Juli\u00e1n, Nahuizalco y Santa Isabel Ishuat\u00e1n.&nbsp;&nbsp;<\/li>\n\n\n\n<li>Fortalecimiento de 18 comit\u00e9s de mujeres, Nahuizalco, San Juli\u00e1n y Santa Isabel Ishuat\u00e1n.&nbsp;&nbsp;<\/li>\n\n\n\n<li>Talleres de formaci\u00f3n a los Comit\u00e9s Intersectoriales acerca del cumplimiento de los derechos de g\u00e9nero en los municipios.&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>Elaboraci\u00f3n de 4 planes de incidencia de Comit\u00e9s Intersectoriales para la incidencia en cuanto a los derechos de las mujeres.<\/li>\n\n\n\n<li>Conformaci\u00f3n de 8 Grupos intercomunitarios de autoayuda, atenci\u00f3n psicol\u00f3gica y autodefensa feminista para mujeres que enfrentan violencia.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>Acciones de incidencia en d\u00edas conmemorativos de las mujeres y pueblos originarios.<\/li>\n\n\n\n<li>Formaci\u00f3n sobre PVG y DSyR a mujeres y hombres j\u00f3venes de los 4 municipios.<\/li>\n\n\n\n<li>Diez talleres de deconstrucci\u00f3n de la masculinidad dirigidos a j\u00f3venes de las 4 redes juveniles en los 4 municipios.<\/li>\n\n\n\n<li>Fortalecimiento de 2 redes juveniles en Santa Isabel Ishuat\u00e1n y San Juli\u00e1n, y creaci\u00f3n de 2 nuevas redes en los municipios de Nahuizalco y Cuisnahuat con \u00e9nfasis en la Prevenci\u00f3n de la VG y&nbsp;&nbsp; los Derechos Sexuales y Reproductivos.&nbsp;<\/li>\n\n\n\n<li>Elaboraci\u00f3n diagn\u00f3stico situacional sobre derechos de la juventud en el municipio de Nahuizalco.<\/li>\n\n\n\n<li>Consultas para la elaboraci\u00f3n de dos pol\u00edticas municipales para la juventud de los Municipios de Nahuizalco y Cuisnahuat.&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>Acciones de incidencia para la exigibilidad de derechos en el marco del D\u00eda Nacional de la Juventud.<\/li>\n\n\n\n<li>Ocho talleres sobre gesti\u00f3n financiera han sido desarrollados para fortalecer las capacidades de administraci\u00f3n de mujeres y j\u00f3venes que ejecutan las 14 iniciativas econ\u00f3micas.&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>Desarrollo de la Escuela Agroecol\u00f3gica Feminista para mujeres y j\u00f3venes de Santa Isabel Ishuat\u00e1n, San Juli\u00e1n, Cuisnahuat y Nahuizalco.&nbsp;&nbsp;&nbsp;<\/li>\n\n\n\n<li>Puesta en marcha de parcelas agroecol\u00f3gicas y m\u00f3dulos de aves mejoradas para la seguridad alimentaria de las familias de los 4 municipios.<\/li>\n\n\n\n<li>Participaci\u00f3n en mercaditos solidarios para mostrar los productos de las 14 iniciativas econ\u00f3micas de los municipios de Santa Isabel Ishuat\u00e1n, San Juli\u00e1n, Nahuizalco y Cuisnahuat.<\/li>\n\n\n\n<li>Giras de intercambio de experiencias de mujeres y j\u00f3venes sobre la producci\u00f3n agropecuaria agroecol\u00f3gica de los 4 municipios con otras experiencias de fincas sustentables.&nbsp;&nbsp;<\/li>\n\n\n\n<li>Formaci\u00f3n de mujeres y j\u00f3venes en talleres t\u00e9cnico vocacionales de los municipios de Nahuizalco y Cuisnahuat (100 participantes entre mujeres y j\u00f3venes).&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/li>\n<\/ul>\n\n\n\n<p><br><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1da54ac e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"1da54ac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b145fb0 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"b145fb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;4&quot;,&quot;slides_to_scroll&quot;:&quot;4&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel de im\u00e1genes\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/Nahuizalco-mujer-indigena-msm-4-300x169.webp\" alt=\"Nahuizalco-mujer-indigena-msm-4\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/Nahuizalco-mujer-indigena-msm-2-300x169.webp\" alt=\"Nahuizalco-mujer-indigena-msm-2\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/manos-unidas-sonsonate-msm-7-300x169.webp\" alt=\"manos-unidas-sonsonate-msm-7\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/manos-unidas-sonsonate-msm-300x169.webp\" alt=\"manos-unidas-sonsonate-msm\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/manos-unidas-sonsonate-msm-1-300x169.webp\" alt=\"manos-unidas-sonsonate-msm-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/03\/IMG_0602-300x200.jpg\" alt=\"Intercambio de semillas\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/03\/IMG_0550-300x200.jpg\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/03\/IMG_0546-300x200.jpg\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2022\/04\/47b4435c-c8d9-47a3-a042-0fb2f1a42fe0-300x169.jpg\" alt=\"47b4435c-c8d9-47a3-a042-0fb2f1a42fe0\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2022\/03\/277246724_4893658097384196_4870672012180481462_n-300x298.jpg\" alt=\"277246724_4893658097384196_4870672012180481462_n\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 de 11\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2022\/03\/277103787_4893658837384122_5389862942806864781_n-1-300x225.jpg\" alt=\"277103787_4893658837384122_5389862942806864781_n\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u00abMujeres y j\u00f3venes organizados defienden sus derechos econ\u00f3micos, sociales, pol\u00edticos y ambientales y promueven la prevenci\u00f3n de la violencia y la seguridad alimentaria en 4 municipios del departamento de Sonsonate\u00bb Objetivo general: contribuir a la defensa y exigibilidad de derechos de las mujeres y j\u00f3venes, promoviendo la prevenci\u00f3n de la violencia y la autonom\u00eda econ\u00f3mica en 4 municipios del departamento de Sonsonate. Breve descripci\u00f3n del proyecto: el proyecto: Mujeres y j\u00f3venes defienden sus derechos econ\u00f3micos, sociales, ambientales y promueven la seguridad alimentaria en 4 municipios del departamento de Sonsonate\u201d, se ejecutar\u00e1 en la zona occidental del pa\u00eds, espec\u00edficamente en el Departamento de Sonsonate, en los municipios de Santa Isabel Ishuat\u00e1n, San Juli\u00e1n, Cuisnahuat y Nahuizalco.\u00a0 Las acciones est\u00e1n dirigidas de manera directa a 1000 mujeres y 800 j\u00f3venes, de esta poblaci\u00f3n existen personas que tienen fortalecida su identidad ind\u00edgena, as\u00ed como otras personas que no se identifican como ind\u00edgenas, a pesar que sus ancestros son ind\u00edgenas locales procedentes de los 4 municipios. Indirectamente se alcanzar\u00e1 una poblaci\u00f3n estimada de 9000 entre mujeres y hombres en los 4 municipios. Resultados del proyecto: R1. Mujeres de 4 asociaciones municipales fortalecen su capacidad de liderazgo y capacidad para la prevenci\u00f3n de la violencia de g\u00e9nero y participan activamente en espacios de toma de decisiones para exigir el cumplimiento de las Pol\u00edticas Municipales de Igualdad de G\u00e9nero. R2. J\u00f3venes de 4 redes municipales fortalecen su capacidad de liderazgo y contralor\u00eda social para dar cumplimiento a las Pol\u00edticas Municipales de Juventud aprobadas. R3. Mujeres y j\u00f3venes mejoran su autonom\u00eda econ\u00f3mica, empleabilidad y seguridad alimentaria a trav\u00e9s de la capacitaci\u00f3n, el fortalecimiento de las iniciativas econ\u00f3micas y los procesos productivos y de comercializaci\u00f3n de sus productos. Ubicaci\u00f3n geogr\u00e1fica: Departamento: Municipios: Comunidades SONSONATE Santa Isabel Ishuat\u00e1n AcachapaLas PiedrasEl CorozalApancoyoAtiluyaMiramar Cuisnahuat Casco urbanoAgua ShucaCoquiamaEl BalsamarSan LucasApancoyo San Juli\u00e1n Casco urbanoAgua ShucaChilataLos LagartosPe\u00f1a BlancaPetacas Nahuizalco Sabana GrandeEl CarrizalTajcuilujlanSisimitepecPusht\u00e1nEl Cerrito 1 departamento 4 municipios 24 comunidades Que se ha ejecutado:<\/p>","protected":false},"author":1,"featured_media":29226,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[179],"tags":[],"class_list":["post-29362","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-proyectos-finalizados"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts\/29362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/comments?post=29362"}],"version-history":[{"count":8,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts\/29362\/revisions"}],"predecessor-version":[{"id":29672,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts\/29362\/revisions\/29672"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/media\/29226"}],"wp:attachment":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/media?parent=29362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/categories?post=29362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/tags?post=29362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}