{"id":22512,"date":"2021-07-13T15:49:02","date_gmt":"2021-07-13T21:49:02","guid":{"rendered":"https:\/\/mujeresmsm.org\/?p=22512"},"modified":"2024-07-27T18:11:00","modified_gmt":"2024-07-28T00:11:00","slug":"mejora-de-las-condiciones-laborales-para-el-acceso-al-trabajo-digno-con-igualdad-y-libre-de-violencia-para-las-mujeres-trabajadoras-en-la-region-centroamericana","status":"publish","type":"post","link":"https:\/\/mujeresmsm.org\/en\/mujeres\/mejora-de-las-condiciones-laborales-para-el-acceso-al-trabajo-digno-con-igualdad-y-libre-de-violencia-para-las-mujeres-trabajadoras-en-la-region-centroamericana\/","title":{"rendered":"MEJORA DE LAS CONDICIONES LABORALES PARA EL ACCESO AL TRABAJO DIGNO, CON IGUALDAD Y LIBRE DE VIOLENCIA PARA LAS MUJERES TRABAJADORAS EN LA REGI\u00d3N CENTROAMERICANA"},"content":{"rendered":"<p><strong>Proyecto: \u201cMEJORA DE LAS CONDICIONES LABORALES PARA EL ACCESO AL TRABAJO DIGNO, CON IGUALDAD Y LIBRE DE VIOLENCIA PARA LAS MUJERES TRABAJADORAS EN LA REGI\u00d3N CENTROAMERICANA (EL SALVADOR, GUATEMALA Y NICARAGUA) CON \u00c9NFASIS EN LAS TRABAJADORAS DE LA INDUSTRIA MAQUILADORA\u00bb<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><em>Este proyecto se ejecuta a nivel de Centro Am\u00e9rica, por la Red Centroamericana de Mujeres en solidaridad con las trabajadoras de las maquilas (REDCAM)<\/em><\/p>\n<p><em>Organizaci\u00f3n de Mujeres Salvadore\u00f1as por la Paz (ORMUSA). El Salvador.<\/em><\/p>\n<p><em>Movimiento de Mujeres Salvadore\u00f1as (MSM). El Salvador. Asociaci\u00f3n de Mujeres en Solidaridad (AMES). Guatemala.<\/em><\/p>\n<p><em>Asociaci\u00f3n de Mujeres Empleadas y Desempleadas Unidas contra la Violencia (AMUCV). Guatemala.<\/em><\/p>\n<p><em>Movimiento de Mujeres Trabajadoras y Desempleas Mar\u00eda Elena Cuadra (MEC). Nicaragua.<\/em><\/p>\n<p><em>Instituto Sindical de Cooperaci\u00f3n al Desarrollo (ISCOD \u2013 PV). Espa\u00f1a.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Este Proyecto est\u00e1 siendo ejecutado en el Municipio de San Marcos San Salvador, son 460 mujeres trabajadoras de la maquila y del sector informal las que se benefician de estas asesor\u00edas.<\/p>\n<p>Estas mujeres provienen de comunidades marginales, municipios aleda\u00f1os y \u00e1rea rural donde presentan escasos recursos econ\u00f3micos; corresponden al perfil de madres solteras y jefas de hogar, madres de ni\u00f1os y ni\u00f1as del Centro de Desarrollo Infantil y Familiar El Jacalito.<\/p>\n<p>Todas ellas ser\u00e1n capacitadas en Derechos de las Mujeres, Derechos Laborales y Prevenci\u00f3n de la Violencia, a su vez que reciben asesor\u00eda jur\u00eddico legal que incluye la asistencia y el acompa\u00f1amiento legal de sus casos, atenci\u00f3n psicol\u00f3gica, atenci\u00f3n v\u00eda telef\u00f3nica y orientaci\u00f3n tras haber sufrido violencia en sus derechos humanos y laborales.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Contexto:<\/strong><\/p>\n<p>Las mujeres de El Salvador, Guatemala, Honduras y Nicaragua sufren graves vulneraciones de sus derechos humanos y laborales: bajos salarios, carencias en la salud y la higiene en el trabajo, alta incidencia de la informalidad, acoso sexual y violencia contra las mujeres\u2026 Problemas agravados por la crisis social y econ\u00f3mica causada por pandemia de COVID \u2013 19.<\/p>\n<p>Particularmente las zonas rurales y francas de estos pa\u00edses son las victimas m\u00e1s vulneradas en derechos de las mujeres trabajadoras, es por eso que el proyecto busca subsanar la falta de informaci\u00f3n que se tiene en derechos laborales y aportar con jornadas de 68 horas semanales de talleres, asesor\u00edas legales y psicol\u00f3gicas para las beneficiadas.<\/p>\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.19.35.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"22503\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.19.35-1024x768.jpeg\" alt=\"\" class=\"wp-image-22503\" srcset=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.19.35-1024x768.jpeg 1024w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.19.35-300x225.jpeg 300w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.19.35-768x576.jpeg 768w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.19.35-800x600.jpeg 800w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.19.35-700x525.jpeg 700w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.19.35.jpeg 1040w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.20.58.jpeg\"><img decoding=\"async\" width=\"720\" height=\"784\" data-id=\"22506\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.20.58.jpeg\" alt=\"\" class=\"wp-image-22506\" srcset=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.20.58.jpeg 720w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.20.58-276x300.jpeg 276w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.20.58-700x762.jpeg 700w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.20.25.jpeg\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"22505\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.20.25-1024x768.jpeg\" alt=\"\" class=\"wp-image-22505\" srcset=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.20.25-1024x768.jpeg 1024w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.20.25-300x225.jpeg 300w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.20.25-768x576.jpeg 768w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.20.25-800x600.jpeg 800w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.20.25-700x525.jpeg 700w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.20.25.jpeg 1040w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.19.55.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"22504\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.19.55-1024x768.jpeg\" alt=\"\" class=\"wp-image-22504\" srcset=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.19.55-1024x768.jpeg 1024w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.19.55-300x225.jpeg 300w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.19.55-768x576.jpeg 768w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.19.55-800x600.jpeg 800w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.19.55-700x525.jpeg 700w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.19.55.jpeg 1040w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.19.08.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"563\" data-id=\"22502\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.19.08.jpeg\" alt=\"\" class=\"wp-image-22502\" srcset=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.19.08.jpeg 1000w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.19.08-300x169.jpeg 300w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.19.08-768x432.jpeg 768w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.19.08-700x394.jpeg 700w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.19.08-539x303.jpeg 539w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.17.58.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"22501\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.17.58-1024x768.jpeg\" alt=\"\" class=\"wp-image-22501\" srcset=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.17.58-1024x768.jpeg 1024w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.17.58-300x225.jpeg 300w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.17.58-768x576.jpeg 768w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.17.58-800x600.jpeg 800w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.17.58-700x525.jpeg 700w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.17.58.jpeg 1040w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.17.58-1.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"22500\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.17.58-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-22500\" srcset=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.17.58-1-1024x768.jpeg 1024w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.17.58-1-300x225.jpeg 300w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.17.58-1-768x576.jpeg 768w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.17.58-1-800x600.jpeg 800w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.17.58-1-700x525.jpeg 700w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2021\/07\/WhatsApp-Image-2021-07-13-at-12.17.58-1.jpeg 1040w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>","protected":false},"excerpt":{"rendered":"<p>Proyecto: \u201cMEJORA DE LAS CONDICIONES LABORALES PARA EL ACCESO AL TRABAJO DIGNO, CON IGUALDAD Y LIBRE DE VIOLENCIA PARA LAS MUJERES TRABAJADORAS EN LA REGI\u00d3N CENTROAMERICANA (EL SALVADOR, GUATEMALA Y NICARAGUA) CON \u00c9NFASIS EN LAS TRABAJADORAS DE LA INDUSTRIA MAQUILADORA\u00bb &nbsp; Este proyecto se ejecuta a nivel de Centro Am\u00e9rica, por la Red Centroamericana de Mujeres en solidaridad con las trabajadoras de las maquilas (REDCAM) Organizaci\u00f3n de Mujeres Salvadore\u00f1as por la Paz (ORMUSA). El Salvador. Movimiento de Mujeres Salvadore\u00f1as (MSM). El Salvador. Asociaci\u00f3n de Mujeres en Solidaridad (AMES). Guatemala. Asociaci\u00f3n de Mujeres Empleadas y Desempleadas Unidas contra la Violencia (AMUCV). Guatemala. Movimiento de Mujeres Trabajadoras y Desempleas Mar\u00eda Elena Cuadra (MEC). Nicaragua. Instituto Sindical de Cooperaci\u00f3n al Desarrollo (ISCOD \u2013 PV). Espa\u00f1a. &nbsp; Este Proyecto est\u00e1 siendo ejecutado en el Municipio de San Marcos San Salvador, son 460 mujeres trabajadoras de la maquila y del sector informal las que se benefician de estas asesor\u00edas. Estas mujeres provienen de comunidades marginales, municipios aleda\u00f1os y \u00e1rea rural donde presentan escasos recursos econ\u00f3micos; corresponden al perfil de madres solteras y jefas de hogar, madres de ni\u00f1os y ni\u00f1as del Centro de Desarrollo Infantil y Familiar El Jacalito. Todas ellas ser\u00e1n capacitadas en Derechos de las Mujeres, Derechos Laborales y Prevenci\u00f3n de la Violencia, a su vez que reciben asesor\u00eda jur\u00eddico legal que incluye la asistencia y el acompa\u00f1amiento legal de sus casos, atenci\u00f3n psicol\u00f3gica, atenci\u00f3n v\u00eda telef\u00f3nica y orientaci\u00f3n tras haber sufrido violencia en sus derechos humanos y laborales. &nbsp; Contexto: Las mujeres de El Salvador, Guatemala, Honduras y Nicaragua sufren graves vulneraciones de sus derechos humanos y laborales: bajos salarios, carencias en la salud y la higiene en el trabajo, alta incidencia de la informalidad, acoso sexual y violencia contra las mujeres\u2026 Problemas agravados por la crisis social y econ\u00f3mica causada por pandemia de COVID \u2013 19. Particularmente las zonas rurales y francas de estos pa\u00edses son las victimas m\u00e1s vulneradas en derechos de las mujeres trabajadoras, es por eso que el proyecto busca subsanar la falta de informaci\u00f3n que se tiene en derechos laborales y aportar con jornadas de 68 horas semanales de talleres, asesor\u00edas legales y psicol\u00f3gicas para las beneficiadas.<\/p>","protected":false},"author":1,"featured_media":22507,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174,179],"tags":[],"class_list":["post-22512","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mujeres","category-proyectos-finalizados"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts\/22512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/comments?post=22512"}],"version-history":[{"count":3,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts\/22512\/revisions"}],"predecessor-version":[{"id":27626,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts\/22512\/revisions\/27626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/media\/22507"}],"wp:attachment":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/media?parent=22512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/categories?post=22512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/tags?post=22512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}