{"id":20497,"date":"2020-03-11T09:47:34","date_gmt":"2020-03-11T15:47:34","guid":{"rendered":"https:\/\/mujeresmsm.org\/?p=20497"},"modified":"2023-05-06T11:09:03","modified_gmt":"2023-05-06T17:09:03","slug":"movimiento-salvadoreno-de-mujeres-insta-a-no-transgredir-el-sistema-democratico","status":"publish","type":"post","link":"https:\/\/mujeresmsm.org\/en\/mujeres\/movimiento-salvadoreno-de-mujeres-insta-a-no-transgredir-el-sistema-democratico\/","title":{"rendered":"Movimiento Salvadore\u00f1o de Mujeres insta a \u201cno transgredir el sistema democr\u00e1tico\u201d"},"content":{"rendered":"<p><strong>Foto Diario Co Latino\/Yaneth Estrada<\/strong><\/p>\n<p>@caricheop<\/p>\n<p>El Movimiento Salvadore\u00f1o de Mujeres (MSM) expres\u00f3 su indignaci\u00f3n y repudio a los intentos del actual gobernante y su cuerpo de seguidores de transgredir las fronteras que en un sistema democr\u00e1tico delimitan las competencias y alcances del \u00f3rgano Ejecutivo, Legislativo y Judicial, tri\u00e1ngulo que en su contenido sustenta cada uno de los poderes que constituyen nuestro sistema pol\u00edtico; esto como parte del foro: \u201cAvances y Retrocesos de la Democracia\u201d.<\/p>\n<p>\u201cNo puede ser que estas alturas venga un gobierno de turno a querer botar todo lo que hemos construido con su prepotencia, con su arrogancia, y ordenar que se le apruebe un pr\u00e9stamo, cuando a\u00fan no ha sido justificado\u201d, afirm\u00f3 Ana Isabel L\u00f3pez, directora del MSM, en relaci\u00f3n a sucesos ocurridos el domingo pasado ante el llamado<br \/>a insurrecci\u00f3n del presidente de la Rep\u00fablica, que gener\u00f3 uso ilegal de la Fuerza Armada de El Salvador (FAES) y la Polic\u00eda Nacional Civil (PNC) en la Asamblea Legislativa, en busca de la aprobaci\u00f3n de un prestamos de $109 millones otorgado por el BCIE para financiamiento del Plan Control Territorial.<\/p>\n<p>Antes estas actuaciones, enfatizaron que \u201cnuestra carta magna no es un instrumento de interpretaci\u00f3n antojadiza, que sus contenidos reflejan los lineamientos claros que en nuestro sistema hay que respetar y que interpretaciones parciales o antojadizas a conveniencia constituyen una violaci\u00f3n\u201d.<\/p>\n<h3>Por la paz y democracia<\/h3>\n<p>\u00a0<\/p>\n<p>Igualmente, el MSM explic\u00f3 que con la firma de los Acuerdos de Paz se intent\u00f3 poner fin a dolorosos a\u00f1os de p\u00e9rdida de nuestros derechos de libre expresi\u00f3n, libertad de tr\u00e1nsito y derecho a la vida; se\u00f1al\u00f3 que el camino democr\u00e1tico de nuestro pa\u00eds est\u00e1 abonado con la sangre, el dolor y la p\u00e9rdida de hombres y mujeres valientes que se insurreccionaron para dejarnos un pa\u00eds libre y soberano.<\/p>\n<p>&#8230;<\/p>\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.diariocolatino.com\/movimiento-salvadoreno-de-mujeres-insta-a-no-transgredir-el-sistema-democratico\/\" target=\"_blank\" rel=\"noreferrer noopener\">VER NOTA ORIGINAL<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0022.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"506\" data-id=\"20506\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0022.jpg\" alt=\"\" class=\"wp-image-20506\" srcset=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0022.jpg 900w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0022-300x169.jpg 300w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0022-768x432.jpg 768w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0022-700x394.jpg 700w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0022-539x303.jpg 539w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0053.jpg\"><img decoding=\"async\" width=\"900\" height=\"506\" data-id=\"20507\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0053.jpg\" alt=\"\" class=\"wp-image-20507\" srcset=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0053.jpg 900w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0053-300x169.jpg 300w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0053-768x432.jpg 768w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0053-700x394.jpg 700w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0053-539x303.jpg 539w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0059.jpg\"><img decoding=\"async\" width=\"900\" height=\"506\" data-id=\"20508\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0059.jpg\" alt=\"\" class=\"wp-image-20508\" srcset=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0059.jpg 900w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0059-300x169.jpg 300w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0059-768x432.jpg 768w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0059-700x394.jpg 700w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0059-539x303.jpg 539w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0074.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" data-id=\"20509\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0074.jpg\" alt=\"\" class=\"wp-image-20509\" srcset=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0074.jpg 900w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0074-300x169.jpg 300w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0074-768x432.jpg 768w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0074-700x394.jpg 700w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0074-539x303.jpg 539w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0093.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" data-id=\"20510\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0093.jpg\" alt=\"\" class=\"wp-image-20510\" srcset=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0093.jpg 900w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0093-300x169.jpg 300w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0093-768x432.jpg 768w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0093-700x394.jpg 700w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2020\/03\/DSC_0093-539x303.jpg 539w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/figure>\n<\/figure>","protected":false},"excerpt":{"rendered":"<p>El Movimiento Salvadore\u00f1o de Mujeres (MSM) expres\u00f3 su indignaci\u00f3n y repudio a los intentos del actual gobernante y su cuerpo de seguidores de transgredir las fronteras que en un sistema democr\u00e1tico delimitan las competencias y alcances del \u00f3rgano Ejecutivo, Legislativo y Judicial, tri\u00e1ngulo que en su contenido sustenta cada uno de los poderes que constituyen nuestro sistema pol\u00edtico; esto como parte del foro: \u201cAvances y Retrocesos de la Democracia\u201d.<\/p>","protected":false},"author":1,"featured_media":20498,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[236],"class_list":["post-20497","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mujeres","tag-reportaje"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts\/20497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/comments?post=20497"}],"version-history":[{"count":12,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts\/20497\/revisions"}],"predecessor-version":[{"id":27553,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts\/20497\/revisions\/27553"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/media\/20498"}],"wp:attachment":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/media?parent=20497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/categories?post=20497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/tags?post=20497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}