{"id":19822,"date":"2020-03-11T09:25:34","date_gmt":"2020-03-11T15:25:34","guid":{"rendered":"https:\/\/mujeresmsm.org\/?p=19822"},"modified":"2023-05-06T09:52:28","modified_gmt":"2023-05-06T15:52:28","slug":"primera-liberacion-de-tortugas-marinas","status":"publish","type":"post","link":"https:\/\/mujeresmsm.org\/en\/archivo\/primera-liberacion-de-tortugas-marinas\/","title":{"rendered":"Primera Liberaci\u00f3n de Tortugas Marinas"},"content":{"rendered":"<p>El viernes 09 de diciembre por la ma\u00f1ana se llev\u00f3 a cabo la primera liberaci\u00f3n de tortugas marinas en la Playa La Tirana, como parte del proyecto de conservaci\u00f3n que se desarrolla en conjunto con las y los habitantes de la zona y con la cooperaci\u00f3n del Fondo de la Iniciativa para Las Am\u00e9ricas FIAES.<\/p>\n<p>A la actividad asistieron representantes de FIAES, de la Alcald\u00eda Municipal de Jiquilisco, personal de Cruz Roja Salvadore\u00f1a y Los Y las tortugueras de la zona junto personal del Movimiento Salvadore\u00f1o de Mujeres.<\/p>\n<p>Las Palabras de apertura estuvieron a Cargo de la Directora General del Movimiento Isabel L\u00f3pez, quien menciono la importancia y la trayectoria que como organizaci\u00f3n se tiene en la zona, de igual manera mencion\u00f3 que este tipo de proyecto ayuda al desarrollo de las personas y de la naturaleza a la vez.<\/p>\n<p>Posteriormente toma la Palabra el representante de FIAES el Ing. Jaime Aguilar quien resalt\u00f3 la importancia de la participaci\u00f3n ciudadana en este tipo de proyectos, y especialmente la esta zona, que con esfuerzo y un doble trabajo trasladaron un vivero antigua y lo reconstruyeron y agrandaron, convirti\u00e9ndolo en el m\u00e1s grande del total de viveros que participan en la zona.<\/p>\n<p>Seguido del Ing. Jaime, hablo El T\u00e9cnico del Proyecto el Ing. Fredys Ch\u00e1vez que expreso su satisfacci\u00f3n y hermandad que tiene con los y las habitantes de la zona pues no es un trabajo de solo uno o de las organizaciones sino de todo un colectivo, a su vez invito al presidente de tortugueros Don L\u00e1zaro y a al joven jefe de la ADESCO a que dieran unas palabras de su trabajo y de experiencia en torno a la conservaci\u00f3n de la tortuga Marina.<\/p>\n<p>Al finalizar el preludio de intervenciones, todos y todas se trasladaron a la orilla del mar para la liberaci\u00f3n, a cada persona se le entrego una tortuguita del total de 600 que se liberaron esas ma\u00f1ana.<\/p>\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/12\/principal-5-1.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"600\" data-id=\"19825\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/12\/principal-5-1.jpg\" alt=\"\" class=\"wp-image-19825\" srcset=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/12\/principal-5-1.jpg 900w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/12\/principal-5-1-300x200.jpg 300w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/12\/principal-5-1-768x512.jpg 768w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/12\/principal-5-1-700x467.jpg 700w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/12\/principal-2-1.jpg\"><img decoding=\"async\" width=\"900\" height=\"600\" data-id=\"19826\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/12\/principal-2-1.jpg\" alt=\"\" class=\"wp-image-19826\" srcset=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/12\/principal-2-1.jpg 900w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/12\/principal-2-1-300x200.jpg 300w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/12\/principal-2-1-768x512.jpg 768w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/12\/principal-2-1-700x467.jpg 700w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/12\/principal-3-1.jpg\"><img decoding=\"async\" width=\"900\" height=\"600\" data-id=\"19827\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/12\/principal-3-1.jpg\" alt=\"\" class=\"wp-image-19827\" srcset=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/12\/principal-3-1.jpg 900w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/12\/principal-3-1-300x200.jpg 300w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/12\/principal-3-1-768x512.jpg 768w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/12\/principal-3-1-700x467.jpg 700w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/12\/principal-4-1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" data-id=\"19828\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/12\/principal-4-1.jpg\" alt=\"\" class=\"wp-image-19828\" srcset=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/12\/principal-4-1.jpg 900w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/12\/principal-4-1-300x200.jpg 300w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/12\/principal-4-1-768x512.jpg 768w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/12\/principal-4-1-700x467.jpg 700w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/figure>\n<\/figure>","protected":false},"excerpt":{"rendered":"<p>El viernes 09 de diciembre por la ma\u00f1ana se llev\u00f3 a cabo la primera liberaci\u00f3n de tortugas marinas en la Playa La Tirana, como parte del proyecto de conservaci\u00f3n que se desarrolla en conjunto con las y los habitantes de la zona y con la cooperaci\u00f3n del Fondo de la Iniciativa para Las Am\u00e9ricas FIAES.<\/p>","protected":false},"author":1,"featured_media":19823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[177,225],"tags":[],"class_list":["post-19822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo","category-medio-ambiente"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts\/19822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/comments?post=19822"}],"version-history":[{"count":3,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts\/19822\/revisions"}],"predecessor-version":[{"id":27533,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts\/19822\/revisions\/27533"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/media\/19823"}],"wp:attachment":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/media?parent=19822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/categories?post=19822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/tags?post=19822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}