{"id":19106,"date":"2014-12-10T08:40:03","date_gmt":"2014-12-10T14:40:03","guid":{"rendered":"https:\/\/mujeresmsm.org\/?p=19106"},"modified":"2019-12-01T08:43:37","modified_gmt":"2019-12-01T14:43:37","slug":"fortaleciendo-el-tejido-organizativo-de-las-mujeres-y-las-alianzas-en-el-ambito-local-y-en-la-prevencion-de-la-violencia-de-genero","status":"publish","type":"post","link":"https:\/\/mujeresmsm.org\/en\/proyectos-finalizados\/fortaleciendo-el-tejido-organizativo-de-las-mujeres-y-las-alianzas-en-el-ambito-local-y-en-la-prevencion-de-la-violencia-de-genero\/","title":{"rendered":"Fortaleciendo el tejido organizativo de las mujeres y las alianzas en el \u00e1mbito local y en la prevenci\u00f3n de la violencia de g\u00e9nero"},"content":{"rendered":"<p>Este proyecto financiado por MANOS UNIDAS, lo ejecutaremos en dos de los municipios en los que contamos con presencia territorial (Nueva Granada, Usulut\u00e1n y Nuevo Ed\u00e9n de San Juan, San Miguel), con el cual pretendemos potenciar en conocimientos especializados en el tema de acceso a la justicia de las mujeres que sufren violencia, as\u00ed mismo capacitaremos a las mujeres en temas de organizaci\u00f3n, liderazgo, prevenci\u00f3n de violencia, etc. Y se Promover a la organizaci\u00f3n de 2 redes juveniles con 30 j\u00f3venes en cada uno de los municipios, desarrollaremos procesos formativos y educativos sobre LEI y PVG en monitoreo y mecanismos de prevenci\u00f3n, a la vez promocionar iniciativas innovadoras en los comit\u00e9s para la implementaci\u00f3n de acciones de PVG tendientes a prevenir problemas relacionadas a: coso sexual, abuso sexual, violencia f\u00edsica, psicol\u00f3gica, sexismo y lenguaje excluyente.<\/p>\n<p>En el municipio de Nueva Granada la estrategia a implementar ser\u00e1: Fortalecer la organizaci\u00f3n de las mujeres a trav\u00e9s de la implementaci\u00f3n del mecanismo de la ventana ciudadana, potenciando las habilidades y capacidades de las mujeres liderezas con una perspectiva, cr\u00edtica y propositiva, en el ejercicio de sus derechos a trav\u00e9s de la controlar\u00eda social, participaci\u00f3n en los procesos de formaci\u00f3n, y la implementaci\u00f3n de acciones, trabajando de forma conjunta con funcionarios\/as p\u00fablicos a fin de lograr cambios en el acceso a la justicia de las mujeres y vivir una vida sin violencia.<\/p>\n<p>En Nuevo Ed\u00e9n de San Juan se trabajara en el fortalecimiento de la organizaci\u00f3n y sensibilizaci\u00f3n en la prevenci\u00f3n de la violencia de g\u00e9nero, a trav\u00e9s de la implementaci\u00f3n de una escuela de debate feminista en el municipio, en ella participaran 40 mujeres seleccionadas de los diferentes comit\u00e9s de mujeres, las cuales ser\u00e1n formadas en 20 talleres durante cuatro meses y luego ellas replicaran los conocimientos adquiridos con las otras mujeres de los diferentes comit\u00e9s. Tambi\u00e9n se realizara una campa\u00f1a de sensibilizaci\u00f3n sobre los derechos de las mujeres y la prevenci\u00f3n de la violencia de g\u00e9nero a nivel local, en donde participaran, gobierno local, actores y actrices del municipio, centros escolares, esta campa\u00f1a ser\u00e1 a trav\u00e9s de festivales, charlas, hojas volantes y socializaci\u00f3n de las dos leyes: Ley Especial para una vida libre de violencia de genero para las Mujeres y Ley de Igualdad para la erradicaci\u00f3n de la discriminaci\u00f3n contra las mujeres.<\/p>\n<p><strong>Lugar:<\/strong> Nueva Granada (Usulut\u00e1n) y Nuevo Ed\u00e9n de san Juan (San Miguel)<br \/>\nCooperante: MANOS UNIDAS<br \/>\n<strong>Pa\u00eds:<\/strong> Espa\u00f1a<br \/>\n<strong>A\u00f1o:<\/strong> 2013-2014<\/p>","protected":false},"excerpt":{"rendered":"<p>Este proyecto financiado por MANOS UNIDAS, lo ejecutaremos en dos de los municipios en los que contamos con presencia territorial (Nueva Granada, Usulut\u00e1n y Nuevo Ed\u00e9n de San Juan, San Miguel), con el cual pretendemos potenciar en conocimientos especializados en el tema de acceso a la justicia de las mujeres que sufren violencia, as\u00ed mismo capacitaremos a las mujeres en temas de organizaci\u00f3n, liderazgo, prevenci\u00f3n de violencia, etc.<\/p>","protected":false},"author":1,"featured_media":18442,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[179],"tags":[],"class_list":["post-19106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-proyectos-finalizados"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts\/19106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/comments?post=19106"}],"version-history":[{"count":1,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts\/19106\/revisions"}],"predecessor-version":[{"id":19107,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts\/19106\/revisions\/19107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/media\/18442"}],"wp:attachment":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/media?parent=19106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/categories?post=19106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/tags?post=19106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}