{"id":18505,"date":"2018-08-21T21:47:08","date_gmt":"2018-08-22T03:47:08","guid":{"rendered":"https:\/\/mujeresmsm.org\/?p=18505"},"modified":"2019-11-24T21:49:29","modified_gmt":"2019-11-25T03:49:29","slug":"la-asociacion-msm-formara-parte-del-fondo-cultural-latinoamericano-en-italia","status":"publish","type":"post","link":"https:\/\/mujeresmsm.org\/en\/mujeres\/la-asociacion-msm-formara-parte-del-fondo-cultural-latinoamericano-en-italia\/","title":{"rendered":"La Asociaci\u00f3n MSM formar\u00e1 parte del Fondo Cultural Latinoamericano en Italia"},"content":{"rendered":"<p>La coordinadora de la Asociaci\u00f3n Marianella Garc\u00eda Villas, Enza D\u00b4Agosto, en su visita a El Salvador, anunci\u00f3 la incorporaci\u00f3n de la Asociaci\u00f3n Movimiento Salvadore\u00f1o de Mujeres (MSM) al Fondo Cultural Latinoamericano, ubicado en la biblioteca Municipal de Sommariva del Bosco en Italia.<\/p>\n<p>El proyecto est\u00e1 ubicado en la biblioteca Municipal de Sommariva del Bosco, cuyo objetivo es brindar un instrumento para la mayor parte de estudiantes y organizaciones que trabajan para El Salvador.<\/p>\n<p>El centro de documentaci\u00f3n de posee una gran cantidad de archivos entre documentos y testimonios que abordan la historia de El Salvador y Latinoam\u00e9rica, que han sido recopilados por las y los miembros de esta asociaci\u00f3n desde el 2015 cuando dio inicio este proyecto.<\/p>\n<p>Oficialmente Fondo Cultural Latinoamericano fue inaugurado en el mes de mayo de este a\u00f1o.<\/p>","protected":false},"excerpt":{"rendered":"<p>La coordinadora de la Asociaci\u00f3n Marianella Garc\u00eda Villas, Enza D\u00b4Agosto, en su visita a El Salvador, anunci\u00f3 la incorporaci\u00f3n de la Asociaci\u00f3n Movimiento Salvadore\u00f1o de Mujeres (MSM) al Fondo Cultural Latinoamericano, ubicado en la biblioteca Municipal de Sommariva del Bosco en Italia.<\/p>","protected":false},"author":1,"featured_media":18506,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[177,174],"tags":[],"class_list":["post-18505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo","category-mujeres"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts\/18505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/comments?post=18505"}],"version-history":[{"count":1,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts\/18505\/revisions"}],"predecessor-version":[{"id":18507,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts\/18505\/revisions\/18507"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/media\/18506"}],"wp:attachment":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/media?parent=18505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/categories?post=18505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/tags?post=18505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}