{"id":18501,"date":"2018-08-20T21:43:10","date_gmt":"2018-08-21T03:43:10","guid":{"rendered":"https:\/\/mujeresmsm.org\/?p=18501"},"modified":"2019-11-24T21:45:46","modified_gmt":"2019-11-25T03:45:46","slug":"tribuna-para-la-divulgacion-de-la-politica-municipal-de-igualdad-de-genero","status":"publish","type":"post","link":"https:\/\/mujeresmsm.org\/en\/mujeres\/tribuna-para-la-divulgacion-de-la-politica-municipal-de-igualdad-de-genero\/","title":{"rendered":"Tribuna para la Divulgaci\u00f3n de la Pol\u00edtica Municipal de Igualdad de G\u00e9nero"},"content":{"rendered":"<p>La Asociaci\u00f3n Movimiento Salvadore\u00f1o de Mujeres (MSM) en coordinaci\u00f3n con la Asociaci\u00f3n de Mujeres Organizadas en la Mesa de G\u00e9nero de Tonacatepeque (AMOMEGTO) y la Unidad de la Mujer de la municipalidad desarrollaron la primera \u201cTribuna para la Divulgaci\u00f3n de la Pol\u00edtica Municipal de Igualdad de G\u00e9nero en el municipio de Tonacatepeque\u201d, frente al mercado municipal de esta localidad.<\/p>\n<p>El MSM tiene 30 a\u00f1os de experiencia y su principal objetivo es la igualdad de derechos y prevenci\u00f3n de violencia. El MSM lleg\u00f3 a Tonacatepeque a partir del 2008 para trabajar en la parte organizativa en 6 cantones del municipio: Cant\u00f3n Veracruz, La Uni\u00f3n, La Fuente, Malacoff, El Sauce y el Transito en una alianza estrat\u00e9gica con ABAZORTO (Asociaci\u00f3n de beneficiarios de agua de la zona rural de Tonacatepeque).<\/p>\n<p>Desde su intervenci\u00f3n, en este municipio el MSM ha ejecutado varios proyecto pero actualmente desarrolla el proyecto: Promoviendo la participaci\u00f3n ciudadana en los municipios de San Marcos y Tonacatepeque en la defensa de los derechos de las mujeres\u201d.<\/p>\n<p>La actividad de participaci\u00f3n ciudadana tiene como objetivo socializar el contenido de la pol\u00edtica de Igualdad de G\u00e9nero para exigir el cumplimento ante el concejo municipal (2018-2021) y a la vez hacer incidencia y contralor\u00eda para exigir un presupuesto etiquetado para la aplicaci\u00f3n de la normativa para la Igualdad de G\u00e9nero.<\/p>\n<p>Desde las actividades de este proyecto se impulsa la campa\u00f1a medi\u00e1tica \u201cPor un municipio con Igualdad de G\u00e9nero\u201d, para contribuir a socializar y exigir el contenido de la pol\u00edtica municipal para la igualdad de g\u00e9nero.<\/p>\n<p>Las asistentes recibieron promocionales y suvenires de la campa\u00f1a a trav\u00e9s de la din\u00e1mica de participaci\u00f3n respondiente a preguntas relacionadas a la participaci\u00f3n ciudadana y contralor\u00eda social as\u00ed como formas de prevenir la violencia contra las mujeres.<\/p>\n<p>De manera indirecta este mensaje lleg\u00f3 a un aproximado 100 ciudadanos y ciudadanas del municipio de Tonacatepeque que escucharon el contenido de la actividad.<\/p>","protected":false},"excerpt":{"rendered":"<p>La Asociaci\u00f3n Movimiento Salvadore\u00f1o de Mujeres (MSM) en coordinaci\u00f3n con la Asociaci\u00f3n de Mujeres Organizadas en la Mesa de G\u00e9nero de Tonacatepeque (AMOMEGTO) y la Unidad de la Mujer de la municipalidad desarrollaron la primera \u201cTribuna para la Divulgaci\u00f3n de la Pol\u00edtica Municipal de Igualdad de G\u00e9nero en el municipio de Tonacatepeque\u201d, frente al mercado municipal de esta localidad.<\/p>","protected":false},"author":1,"featured_media":18502,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[177,176,174,175],"tags":[186],"class_list":["post-18501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivo","category-juventud","category-mujeres","category-ninez","tag-tonacatepeque"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts\/18501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/comments?post=18501"}],"version-history":[{"count":1,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts\/18501\/revisions"}],"predecessor-version":[{"id":18503,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/posts\/18501\/revisions\/18503"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/media\/18502"}],"wp:attachment":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/media?parent=18501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/categories?post=18501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/tags?post=18501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}