{"id":13396,"date":"2014-03-24T10:54:51","date_gmt":"2014-03-24T10:54:51","guid":{"rendered":"http:\/\/demo.qodeinteractive.com\/bridge28\/?page_id=13396"},"modified":"2023-09-25T09:59:22","modified_gmt":"2023-09-25T15:59:22","slug":"quienes-somos","status":"publish","type":"page","link":"https:\/\/mujeresmsm.org\/en\/quienes-somos\/","title":{"rendered":"Qui\u00e9nes Somos"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"13396\" class=\"elementor elementor-13396\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b19e16 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"2b19e16\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a0c610c e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"a0c610c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b8d3a5 elementor-widget elementor-widget-shortcode\" data-id=\"8b8d3a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/mujeresmsm.org\/en\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tQui\u00e9nes Somos\n\t\t<\/span><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3cfe24f e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"3cfe24f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8497357 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"8497357\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e73b193 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"e73b193\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>Somos una organizaci\u00f3n de Mujeres que surge en pleno conflicto armado 1988<\/h3><div><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-28653 size-medium\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/lucha-msm-300x169.webp\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/lucha-msm-300x169.webp 300w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/lucha-msm-1024x576.webp 1024w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/lucha-msm-768x432.webp 768w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/lucha-msm-1536x864.webp 1536w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/lucha-msm.webp 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><h2>Credibilidad, Confianza y Prestigio<\/h2><p>En la lucha por los derechos de las mujeres, el MSM ha enfocado sus esfuerzos en tres \u00e1mbitos estrat\u00e9gicos: internacional, nacional y territorial.<\/p><p>En el \u00e1mbito internacional y nacional, realizando gestiones con las agencias de cooperaci\u00f3n para que apoyen las necesidades identificadas en los grupos de mujeres, as\u00ed como la coordinaci\u00f3n interinstitucional con otros organismos afines, cuyo prop\u00f3sito es luchar por los derechos de las mujeres. En el \u00e1mbito territorial, organizando a las mujeres en comit\u00e9s y asociaciones para que sean ellas las protagonistas en la implementaci\u00f3n de los proyectos que se ejecutan en sus respectivas comunidades y al mismo tiempo sean capaces de gestionar, ante las autoridades locales, la soluci\u00f3n a los problemas y necesidades que enfrentan.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d3256f e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"3d3256f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3b9b1b2 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"3b9b1b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">El MSM, en sus 35 a\u00f1os de existencia, ha venido construyendo trabajo planificado, organizado y sistematizado a trav\u00e9s de proyectos enfocados a promover los derechos econ\u00f3micos, pol\u00edticos, sociales, culturales y ambientales de las mujeres del campo y la ciudad.<\/p>\n<p style=\"text-align: left;\">\n<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a991d1 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"5a991d1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b0aaffa elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"b0aaffa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"text-align: center;\">Coordinaci\u00f3n Inter-Institucional<\/h2>\n<div>&nbsp;<\/div>\n<p>El conocimiento, reivindicaci\u00f3n y aplicaci\u00f3n de los derechos de las mujeres, la juventud y la ni\u00f1ez es una tarea y esfuerzo que requiere de la participaci\u00f3n de diferentes instituciones nacionales e internacionales, as\u00ed como de la sociedad civil organizada. El MSM, como movimiento feminista, est\u00e1 consciente que para el logro de la misi\u00f3n y visi\u00f3n debe aunar y coordinar esfuerzos interinstitucionales. Por ello el MSM es parte activa de diferentes espacios de coordinaci\u00f3n y concertaci\u00f3n a nivel nacional e internacional. Adem\u00e1s desde las estructuras interinstitucionales posicionamos la sociedad civil de mujeres organizadas para la implementaci\u00f3n de acciones dirigidas a las mujeres de los municipios.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dec7bb0 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"dec7bb0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d34e7e9 elementor-widget elementor-widget-gallery\" data-id=\"d34e7e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;lazyload&quot;:&quot;yes&quot;,&quot;gallery_layout&quot;:&quot;grid&quot;,&quot;columns&quot;:4,&quot;columns_tablet&quot;:2,&quot;columns_mobile&quot;:1,&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;aspect_ratio&quot;:&quot;3:2&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/Reunion-con-cooperantes.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d34e7e9\" data-elementor-lightbox-title=\"Reuni\u00f3n con cooperantes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkyMzUsInVybCI6Imh0dHBzOlwvXC9tdWplcmVzbXNtLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDlcL1JldW5pb24tY29uLWNvb3BlcmFudGVzLmpwZyIsInNsaWRlc2hvdyI6ImQzNGU3ZTkifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/Reunion-con-cooperantes-768x495.jpg\" data-width=\"768\" data-height=\"495\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/Reunion-con-cooperantes6.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d34e7e9\" data-elementor-lightbox-title=\"Reuni\u00f3n con cooperantes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkyMzcsInVybCI6Imh0dHBzOlwvXC9tdWplcmVzbXNtLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDlcL1JldW5pb24tY29uLWNvb3BlcmFudGVzNi5qcGciLCJzbGlkZXNob3ciOiJkMzRlN2U5In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/Reunion-con-cooperantes6-768x500.jpg\" data-width=\"768\" data-height=\"500\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/Reunion-con-cooperantes7.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d34e7e9\" data-elementor-lightbox-title=\"Reuni\u00f3n con cooperantes7\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkyMzgsInVybCI6Imh0dHBzOlwvXC9tdWplcmVzbXNtLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDlcL1JldW5pb24tY29uLWNvb3BlcmFudGVzNy5qcGciLCJzbGlkZXNob3ciOiJkMzRlN2U5In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/Reunion-con-cooperantes7-768x507.jpg\" data-width=\"768\" data-height=\"507\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/Reunion-con-cooperantes11.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d34e7e9\" data-elementor-lightbox-title=\"Reuni\u00f3n con cooperantes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkyMzksInVybCI6Imh0dHBzOlwvXC9tdWplcmVzbXNtLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDlcL1JldW5pb24tY29uLWNvb3BlcmFudGVzMTEuanBnIiwic2xpZGVzaG93IjoiZDM0ZTdlOSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/Reunion-con-cooperantes11-768x507.jpg\" data-width=\"768\" data-height=\"507\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/Reunion-con-cooperantes14.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d34e7e9\" data-elementor-lightbox-title=\"Reuni\u00f3n con cooperantes14\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkyNDAsInVybCI6Imh0dHBzOlwvXC9tdWplcmVzbXNtLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDlcL1JldW5pb24tY29uLWNvb3BlcmFudGVzMTQuanBnIiwic2xpZGVzaG93IjoiZDM0ZTdlOSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/Reunion-con-cooperantes14-768x502.jpg\" data-width=\"768\" data-height=\"502\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/Reunion-con-cooperantes16.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d34e7e9\" data-elementor-lightbox-title=\"Reuni\u00f3n con cooperantes16\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkyNDEsInVybCI6Imh0dHBzOlwvXC9tdWplcmVzbXNtLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDlcL1JldW5pb24tY29uLWNvb3BlcmFudGVzMTYuanBnIiwic2xpZGVzaG93IjoiZDM0ZTdlOSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/Reunion-con-cooperantes16-768x497.jpg\" data-width=\"768\" data-height=\"497\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/Reunion-con-cooperantes12.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d34e7e9\" data-elementor-lightbox-title=\"Reuni\u00f3n con cooperantes12\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkyNDIsInVybCI6Imh0dHBzOlwvXC9tdWplcmVzbXNtLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDlcL1JldW5pb24tY29uLWNvb3BlcmFudGVzMTIuanBnIiwic2xpZGVzaG93IjoiZDM0ZTdlOSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/Reunion-con-cooperantes12-768x503.jpg\" data-width=\"768\" data-height=\"503\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/Reunion-con-cooperantes15.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"d34e7e9\" data-elementor-lightbox-title=\"Reuni\u00f3n con cooperantes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjkyNDMsInVybCI6Imh0dHBzOlwvXC9tdWplcmVzbXNtLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDlcL1JldW5pb24tY29uLWNvb3BlcmFudGVzMTUuanBnIiwic2xpZGVzaG93IjoiZDM0ZTdlOSJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/Reunion-con-cooperantes15-768x499.jpg\" data-width=\"768\" data-height=\"499\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2404bb0 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"2404bb0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d49755b e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-child\" data-id=\"d49755b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9c62207 elementor-widget elementor-widget-text-editor\" data-id=\"9c62207\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Reuni\u00f3n mensual con el personal de MSM como mecanismo de evaluaci\u00f3n y seguimiento a la ejecuci\u00f3n de proyectos, la ejecuci\u00f3n del Plan Operativo y Plan Estrat\u00e9gico<\/h2><p>En el MSM existen mecanismos de coordinaci\u00f3n y comunicaci\u00f3n, formal e informal, que se dan en el marco de una relaci\u00f3n horizontal entre el personal, esto favorece la din\u00e1mica de trabajo institucional. El principal mecanismo formal de coordinaci\u00f3n y comunicaci\u00f3n son las reuniones ordinarias y extraordinarias que se dan en la estructura organizativa. En primer lugar, las reuniones ordinarias y extraordinarias de las integrantes de la Junta directiva que se realiza una reuni\u00f3n cada dos meses. En segundo lugar, las reuniones bilaterales entre la presidenta de la Junta directiva y la direcci\u00f3n ejecutiva. En tercer lugar, las reuniones entre la Direcci\u00f3n General, las coordinadoras de programas y promotoras cada mes. Tambien reuniones de direcci\u00f3n ejecutiva y equipo de conducci\u00f3n formada por las corrdinadoras de proyectos, cada vez que es necesario. Por \u00faltimo, las reuniones que realizan las\/os t\u00e9cnicas\/os y promotoras\/es con los comit\u00e9s y asociaciones de mujeres, en el \u00e1mbito territorial. El otro mecanismo de coordinaci\u00f3n y comunicaci\u00f3n, m\u00e1s informal y no por ello menos importante, es el que se da a la hora de las comidas, celebraciones de cumplea\u00f1os, convivios, jornadas de capacitaci\u00f3n y evaluaci\u00f3n, marchas, viajes a los municipios, entre otros. En general, se puede afirmar que en el MSM existen los mecanismos y los espacios, formales e informales, para que el personal pueda llegar a coordinar actividades conjuntas, comunicar resultados, apoyar iniciativas, discrepar con algo que no le parece, consensuar acuerdos, entre otros.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-102a275 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"102a275\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Transparencia, cumplimiento de responsabilidades t\u00e9cnicas y financieras con las instituciones nacionales, la cooperaci\u00f3n internacional que apoya y soporta el quehacer de MSM&nbsp;<\/h2>\n<p>El MSM ha venido institucionalizando gradualmente una cultura de generaci\u00f3n de informaci\u00f3n sistematizada de los procesos t\u00e9cnicos, administrativos y financieros. A nivel t\u00e9cnico se elaboran planes estrat\u00e9gicos y operativos, planificaciones e informes mensuales, informes de avance de los planes operativos y\/o proyectos, memorias de evaluaci\u00f3n, informes semestrales y finales de proyectos, diagn\u00f3sticos comunitarios, l\u00edneas de base, estudios de mercado, informes de consultor\u00edas, entre otros. En el plano administrativo existen los Estatutos, manual de funciones, reglamento interno y memoria de labores anual. En la dimensi\u00f3n financiera se elaboran presupuestos, reporte de ingresos y egresos, liquidaciones de proyectos, estados financieros y otros m\u00e1s. Toda la informaci\u00f3n generada, procesada y sistematizada a nivel t\u00e9cnico, administrativo y financiero, fortalece el buen funcionamiento y la institucionalidad del MSM, lo que favorece y facilita la gesti\u00f3n que realiza la Direcci\u00f3n ejecutiva y las coordinaciones de los programas de Educaci\u00f3n y capacitaci\u00f3n, Desarrollo local y Fortalecimiento institucional.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b87fe14 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"b87fe14\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c81978c gallery-spacing-custom elementor-widget__width-initial elementor-widget elementor-widget-image-gallery\" data-id=\"c81978c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t<div id='gallery-1' class='gallery galleryid-13396 gallery-columns-5 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c81978c\" data-elementor-lightbox-title=\"photo_5176890696991353675_y\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg2ODYsInVybCI6Imh0dHBzOlwvXC9tdWplcmVzbXNtLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDlcL3Bob3RvXzUxNzY4OTA2OTY5OTEzNTM2NzVfeS5qcGciLCJzbGlkZXNob3ciOiJjODE5NzhjIn0%3D\" href='https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/photo_5176890696991353675_y.jpg'><img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/photo_5176890696991353675_y-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/photo_5176890696991353675_y-300x225.jpg 300w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/photo_5176890696991353675_y-1024x768.jpg 1024w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/photo_5176890696991353675_y-768x576.jpg 768w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/photo_5176890696991353675_y.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c81978c\" data-elementor-lightbox-title=\"100_2492\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg2NTEsInVybCI6Imh0dHBzOlwvXC9tdWplcmVzbXNtLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAxOVwvMTFcLzEwMF8yNDkyLmpwZyIsInNsaWRlc2hvdyI6ImM4MTk3OGMifQ%3D%3D\" href='https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/11\/100_2492.jpg'><img decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/11\/100_2492-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/11\/100_2492-300x225.jpg 300w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/11\/100_2492.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c81978c\" data-elementor-lightbox-title=\"DSC06102\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg2NTMsInVybCI6Imh0dHBzOlwvXC9tdWplcmVzbXNtLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAxOVwvMTFcL0RTQzA2MTAyLmpwZyIsInNsaWRlc2hvdyI6ImM4MTk3OGMifQ%3D%3D\" href='https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/11\/DSC06102.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/11\/DSC06102-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/11\/DSC06102-300x225.jpg 300w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/11\/DSC06102.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c81978c\" data-elementor-lightbox-title=\"DSC06869\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg2NTQsInVybCI6Imh0dHBzOlwvXC9tdWplcmVzbXNtLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAxOVwvMTFcL0RTQzA2ODY5LmpwZyIsInNsaWRlc2hvdyI6ImM4MTk3OGMifQ%3D%3D\" href='https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/11\/DSC06869.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/11\/DSC06869-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/11\/DSC06869-300x225.jpg 300w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2019\/11\/DSC06869.jpg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"c81978c\" data-elementor-lightbox-title=\"photo_5176890696991353673_y\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjg2ODgsInVybCI6Imh0dHBzOlwvXC9tdWplcmVzbXNtLm9yZ1wvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyM1wvMDlcL3Bob3RvXzUxNzY4OTA2OTY5OTEzNTM2NzNfeS5qcGciLCJzbGlkZXNob3ciOiJjODE5NzhjIn0%3D\" href='https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/photo_5176890696991353673_y.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/photo_5176890696991353673_y-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/photo_5176890696991353673_y-300x225.jpg 300w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/photo_5176890696991353673_y-1024x768.jpg 1024w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/photo_5176890696991353673_y-768x576.jpg 768w, https:\/\/mujeresmsm.org\/wp-content\/uploads\/2023\/09\/photo_5176890696991353673_y.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5b2229d e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"5b2229d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d95fc44 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-column-slider-no wpr-equal-height-no e-con e-parent\" data-id=\"d95fc44\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Somos una organizaci\u00f3n de Mujeres que surge en pleno conflicto armado 1988 Credibilidad, Confianza y Prestigio En la lucha por los derechos de las mujeres, el MSM ha enfocado sus esfuerzos en tres \u00e1mbitos estrat\u00e9gicos: internacional, nacional y territorial. En el \u00e1mbito internacional y nacional, realizando gestiones con las agencias de cooperaci\u00f3n para que apoyen las necesidades identificadas en los grupos de mujeres, as\u00ed como la coordinaci\u00f3n interinstitucional con otros organismos afines, cuyo prop\u00f3sito es luchar por los derechos de las mujeres. En el \u00e1mbito territorial, organizando a las mujeres en comit\u00e9s y asociaciones para que sean ellas las protagonistas en la implementaci\u00f3n de los proyectos que se ejecutan en sus respectivas comunidades y al mismo tiempo sean capaces de gestionar, ante las autoridades locales, la soluci\u00f3n a los problemas y necesidades que enfrentan. El MSM, en sus 35 a\u00f1os de existencia, ha venido construyendo trabajo planificado, organizado y sistematizado a trav\u00e9s de proyectos enfocados a promover los derechos econ\u00f3micos, pol\u00edticos, sociales, culturales y ambientales de las mujeres del campo y la ciudad. Coordinaci\u00f3n Inter-Institucional &nbsp; El conocimiento, reivindicaci\u00f3n y aplicaci\u00f3n de los derechos de las mujeres, la juventud y la ni\u00f1ez es una tarea y esfuerzo que requiere de la participaci\u00f3n de diferentes instituciones nacionales e internacionales, as\u00ed como de la sociedad civil organizada. El MSM, como movimiento feminista, est\u00e1 consciente que para el logro de la misi\u00f3n y visi\u00f3n debe aunar y coordinar esfuerzos interinstitucionales. Por ello el MSM es parte activa de diferentes espacios de coordinaci\u00f3n y concertaci\u00f3n a nivel nacional e internacional. Adem\u00e1s desde las estructuras interinstitucionales posicionamos la sociedad civil de mujeres organizadas para la implementaci\u00f3n de acciones dirigidas a las mujeres de los municipios. Reuni\u00f3n mensual con el personal de MSM como mecanismo de evaluaci\u00f3n y seguimiento a la ejecuci\u00f3n de proyectos, la ejecuci\u00f3n del Plan Operativo y Plan Estrat\u00e9gico En el MSM existen mecanismos de coordinaci\u00f3n y comunicaci\u00f3n, formal e informal, que se dan en el marco de una relaci\u00f3n horizontal entre el personal, esto favorece la din\u00e1mica de trabajo institucional. El principal mecanismo formal de coordinaci\u00f3n y comunicaci\u00f3n son las reuniones ordinarias y extraordinarias que se dan en la estructura organizativa. En primer lugar, las reuniones ordinarias y extraordinarias de las integrantes de la Junta directiva que se realiza una reuni\u00f3n cada dos meses. En segundo lugar, las reuniones bilaterales entre la presidenta de la Junta directiva y la direcci\u00f3n ejecutiva. En tercer lugar, las reuniones entre la Direcci\u00f3n General, las coordinadoras de programas y promotoras cada mes. Tambien reuniones de direcci\u00f3n ejecutiva y equipo de conducci\u00f3n formada por las corrdinadoras de proyectos, cada vez que es necesario. Por \u00faltimo, las reuniones que realizan las\/os t\u00e9cnicas\/os y promotoras\/es con los comit\u00e9s y asociaciones de mujeres, en el \u00e1mbito territorial. El otro mecanismo de coordinaci\u00f3n y comunicaci\u00f3n, m\u00e1s informal y no por ello menos importante, es el que se da a la hora de las comidas, celebraciones de cumplea\u00f1os, convivios, jornadas de capacitaci\u00f3n y evaluaci\u00f3n, marchas, viajes a los municipios, entre otros. En general, se puede afirmar que en el MSM existen los mecanismos y los espacios, formales e informales, para que el personal pueda llegar a coordinar actividades conjuntas, comunicar resultados, apoyar iniciativas, discrepar con algo que no le parece, consensuar acuerdos, entre otros. Transparencia, cumplimiento de responsabilidades t\u00e9cnicas y financieras con las instituciones nacionales, la cooperaci\u00f3n internacional que apoya y soporta el quehacer de MSM&nbsp; El MSM ha venido institucionalizando gradualmente una cultura de generaci\u00f3n de informaci\u00f3n sistematizada de los procesos t\u00e9cnicos, administrativos y financieros. A nivel t\u00e9cnico se elaboran planes estrat\u00e9gicos y operativos, planificaciones e informes mensuales, informes de avance de los planes operativos y\/o proyectos, memorias de evaluaci\u00f3n, informes semestrales y finales de proyectos, diagn\u00f3sticos comunitarios, l\u00edneas de base, estudios de mercado, informes de consultor\u00edas, entre otros. En el plano administrativo existen los Estatutos, manual de funciones, reglamento interno y memoria de labores anual. En la dimensi\u00f3n financiera se elaboran presupuestos, reporte de ingresos y egresos, liquidaciones de proyectos, estados financieros y otros m\u00e1s. Toda la informaci\u00f3n generada, procesada y sistematizada a nivel t\u00e9cnico, administrativo y financiero, fortalece el buen funcionamiento y la institucionalidad del MSM, lo que favorece y facilita la gesti\u00f3n que realiza la Direcci\u00f3n ejecutiva y las coordinaciones de los programas de Educaci\u00f3n y capacitaci\u00f3n, Desarrollo local y Fortalecimiento institucional.<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-13396","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/pages\/13396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/comments?post=13396"}],"version-history":[{"count":127,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/pages\/13396\/revisions"}],"predecessor-version":[{"id":29250,"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/pages\/13396\/revisions\/29250"}],"wp:attachment":[{"href":"https:\/\/mujeresmsm.org\/en\/wp-json\/wp\/v2\/media?parent=13396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}